{"id":3330,"date":"2011-04-09T10:54:27","date_gmt":"2011-04-09T09:54:27","guid":{"rendered":"http:\/\/www.escolasdesoure.pt\/web\/?p=3330"},"modified":"2011-04-09T10:54:27","modified_gmt":"2011-04-09T09:54:27","slug":"esma-a-descoberta-de-paris","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2011\/04\/esma-a-descoberta-de-paris\/","title":{"rendered":"ESMA \u00e0 Descoberta de Paris"},"content":{"rendered":"<p style=\"text-align: justify;\">No dia 5 de Mar\u00e7o, um grupo de 34 alunos dos7\u00ba, 8\u00ba, 9\u00baanos e do CEF-SM partiu da Escola 3 \/ Sec Martinho \u00c1rias \u00e0 descoberta da capital francesa, no \u00e2mbito de um projecto dinamizado pelas Professoras de Franc\u00eas daquela institui\u00e7\u00e3o, com a colabora\u00e7\u00e3o da Assistente de L\u00edngua.<br \/>\nAo longo da semana, os alunos tiveram o privil\u00e9gio de apreciar in loco a cultura e a civiliza\u00e7\u00e3o francesas, conhecidas, at\u00e9 ao momento, atrav\u00e9s dos livros e do multim\u00e9dia. Esta iniciativa proporcionou-lhes momentos singulares de contacto com uma realidade europeia diferente da nossa e, por isso, enriquecedores em termos de forma\u00e7\u00e3o integral do aluno. A Catedral de Notre-Dame, a Torre Eiffel, o Museu do Louvre a Bas\u00edlica do Sacr\u00e9-Coeur foram alguns dos monumentos emblem\u00e1ticos da cidade-luz que encantaram e emocionaram aqueles jovens estudantes de Soure. No passeio nocturno pelo rio Sena, a bordo do Bateau-Mouche, o grupo circundou a famosa \u00cele de La Cit\u00e9, ber\u00e7o da cidade de Paris, contemplando a beleza arquitect\u00f3nica do patrim\u00f3nio cultural franc\u00eas. Ao longo das avenidas, nomeadamente a famosa Champs Elys\u00e9es, os alunos conviveram com o quotidiano dos franceses. O Pal\u00e1cio de Lu\u00eds XIV, em Versalhes, levou-os tamb\u00e9m aos costumes da Corte francesa e \u00e0 beleza dos jardins de Andr\u00e9 Le N\u00f4tre. Associando a componente cultural \u00e0 l\u00fadica, a Disneyl\u00e2ndia de Paris e o Futuroscope, em Poitiers foram palcos de sensa\u00e7\u00f5es fortes e inesquec\u00edveis proporcionadas pelas novas tecnologias.<br \/>\nEste projecto, que contou com a colabora\u00e7\u00e3o de toda a Comunidade Escolar e Educativa, nomeadamente das Entidades P\u00fablicas e Privadas, \u00e0s quais reiteramos os nossos agradecimentos, representa, sem d\u00favida alguma, uma mais-valia para os aprendentes da l\u00edngua francesa.<\/p>\n<p style=\"text-align: right;\">As professoras de Franc\u00eas<\/p>\n<div id='gallery-1' class='gallery galleryid-3330 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2011\/04\/1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2011\/04\/1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2011\/04\/2.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2011\/04\/2-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2011\/04\/3.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2011\/04\/3-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>No dia 5 de Mar\u00e7o, um grupo de 34 alunos dos7\u00ba, 8\u00ba, 9\u00baanos e do CEF-SM partiu da Escola 3 \/ Sec Martinho \u00c1rias \u00e0<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2011\/04\/esma-a-descoberta-de-paris\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;ESMA \u00e0 Descoberta de Paris&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3330","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/3330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=3330"}],"version-history":[{"count":3,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/3330\/revisions"}],"predecessor-version":[{"id":3336,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/3330\/revisions\/3336"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=3330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=3330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=3330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}