{"id":3273,"date":"2011-03-30T22:51:48","date_gmt":"2011-03-30T21:51:48","guid":{"rendered":"http:\/\/www.escolasdesoure.pt\/web\/?p=3273"},"modified":"2011-03-30T22:56:57","modified_gmt":"2011-03-30T21:56:57","slug":"spo-semana-de-informacao-escolar-e-profissional","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2011\/03\/spo-semana-de-informacao-escolar-e-profissional\/","title":{"rendered":"SPO: Semana  de Informa\u00e7\u00e3o Escolar e Profissional"},"content":{"rendered":"<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"alignleft\" src=\"http:\/\/4.bp.blogspot.com\/_W-wAZNYBeFk\/TAVrSdZLJ1I\/AAAAAAAAAEk\/FDl-04RoTnI\/s400\/vocacao%5B1%5D.png\" alt=\"\" width=\"204\" height=\"178\" \/>O Servi\u00e7o de Psicologia e Orienta\u00e7\u00e3o vai levar a efeito de <span style=\"text-decoration: underline;\"><strong>4 a 8 de Abril de 2011<\/strong><\/span> a \u201cSemana  de Informa\u00e7\u00e3o Escolar e Profissional\u201d. Constitui objectivo fundamental do programa elaborado para esta semana, a promo\u00e7\u00e3o de atitudes de procura e tratamento de informa\u00e7\u00e3o de natureza escolar e profissional, para que os alunos se possam situar perante as oportunidades dispon\u00edveis, tanto no dom\u00ednio dos estudos e forma\u00e7\u00f5es, como no das actividades profissionais.<br \/>\nTendo em conta os objectivos definidos, foram convidadas diversas escolas de ensino superior a participar nesta semana com cartazes, brochuras e alguns elementos das respectivas institui\u00e7\u00f5es que possam esclarecer as d\u00favidas dos nossos alunos.<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/docs.google.com\/viewer?a=v&amp;pid=explorer&amp;chrome=true&amp;srcid=0B8uHoijqUNxIZDU0MGU4OTUtYjNmOC00ZjI1LTkxYWQtZWU3YmQ5Y2Q4YTA0&amp;hl=pt_PT\" target=\"_blank\">Ver programa<\/a><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Servi\u00e7o de Psicologia e Orienta\u00e7\u00e3o vai levar a efeito de 4 a 8 de Abril de 2011 a \u201cSemana de Informa\u00e7\u00e3o Escolar e Profissional\u201d.<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2011\/03\/spo-semana-de-informacao-escolar-e-profissional\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;SPO: Semana  de Informa\u00e7\u00e3o Escolar e Profissional&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3273","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/3273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=3273"}],"version-history":[{"count":11,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/3273\/revisions"}],"predecessor-version":[{"id":3275,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/3273\/revisions\/3275"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=3273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=3273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}