{"id":2957,"date":"2011-01-31T14:41:11","date_gmt":"2011-01-31T14:41:11","guid":{"rendered":"http:\/\/www.escolasdesoure.pt\/web\/?p=2957"},"modified":"2011-01-31T14:41:11","modified_gmt":"2011-01-31T14:41:11","slug":"dia-de-reis","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2011\/01\/dia-de-reis\/","title":{"rendered":"Dia de Reis"},"content":{"rendered":"<p style=\"text-align: justify;\">No dia seis de Janeiro de 2011 os alunos da EB1 de Sobral e do Jardim de Inf\u00e2ncia e as suas professoras cantaram os reis pela aldeia do Sobral.<br \/>\nCome\u00e7aram por visitar o Lar de Idosos onde cantaram e ofereceram uma lembran\u00e7a aos idosos. Como agradecimento pela sua presen\u00e7a foi-lhes oferecido imensas guloseimas!<br \/>\nDe seguida seguiu-se a romaria pela localidade. As pessoas aderiram com muita alegria, revivendo esta tradi\u00e7\u00e3o de forma entusiasta e deram a sua oferta, na maioria doces.<br \/>\nFoi com grande satisfa\u00e7\u00e3o que os alunos aprenderam a lenda do Bolo-Rei e participaram na confec\u00e7\u00e3o do mesmo, n\u00e3o esquecendo de lhe colocar a tradicional FAVA!<br \/>\nPuderam ainda saborear o Bolo-Rei num lanche conv\u00edvio e os felizes contemplados com a fava foram o Guilherme e a professora Paula!<\/p>\n<p style=\"text-align: justify;\">[nggallery id=36]<\/p>\n<p style=\"text-align: justify;\">Paula Mendes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia seis de Janeiro de 2011 os alunos da EB1 de Sobral e do Jardim de Inf\u00e2ncia e as suas professoras cantaram os reis<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2011\/01\/dia-de-reis\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;Dia de Reis&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[168],"class_list":["post-2957","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-eb1-de-sobral"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/2957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=2957"}],"version-history":[{"count":2,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/2957\/revisions"}],"predecessor-version":[{"id":2960,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/2957\/revisions\/2960"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=2957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=2957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=2957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}