{"id":19739,"date":"2024-10-23T09:32:27","date_gmt":"2024-10-23T08:32:27","guid":{"rendered":"https:\/\/www.escolasdesoure.pt\/web\/?p=19739"},"modified":"2024-10-23T09:32:27","modified_gmt":"2024-10-23T08:32:27","slug":"recolha-de-generos-alimentares","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2024\/10\/recolha-de-generos-alimentares\/","title":{"rendered":"Recolha de g\u00e9neros alimentares"},"content":{"rendered":"\n<p>Como forma de agradecimento pelo empenho que todos &#8211; encarregados de educa\u00e7\u00e3o e seus educandos, professoras e assistentes operacionais &#8211; tiveram na recolha de g\u00e9neros alimentares para doar \u00e0 Associa\u00e7\u00e3o Sourepatas, partilhamos aqui algumas fotografias que ficar\u00e3o como lembran\u00e7a do qu\u00e3o \u00e9 t\u00e3o bom podermos ajudar quem tanto necessita (seja por ter nascido na rua ou abandonado).<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0002-3.jpg\"><img decoding=\"async\" width=\"675\" height=\"900\" data-id=\"19741\" src=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0002-3-675x900.jpg\" alt=\"\" class=\"wp-image-19741\" srcset=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0002-3-675x900.jpg 675w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0002-3-225x300.jpg 225w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0002-3-768x1024.jpg 768w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0002-3.jpg 900w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0000-2.jpg\"><img decoding=\"async\" width=\"675\" height=\"900\" data-id=\"19742\" src=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0000-2-675x900.jpg\" alt=\"\" class=\"wp-image-19742\" srcset=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0000-2-675x900.jpg 675w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0000-2-225x300.jpg 225w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0000-2-768x1024.jpg 768w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0000-2.jpg 900w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0004-1.jpg\"><img decoding=\"async\" width=\"675\" height=\"900\" data-id=\"19740\" src=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0004-1-675x900.jpg\" alt=\"\" class=\"wp-image-19740\" srcset=\"https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0004-1-675x900.jpg 675w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0004-1-225x300.jpg 225w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0004-1-768x1024.jpg 768w, https:\/\/www.escolasdesoure.pt\/web\/wp-content\/uploads\/2024\/10\/IMG-20241017-WA0004-1.jpg 900w\" sizes=\"(max-width: 675px) 100vw, 675px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Como forma de agradecimento pelo empenho que todos &#8211; encarregados de educa\u00e7\u00e3o e seus educandos, professoras e assistentes operacionais &#8211; tiveram na recolha de g\u00e9neros<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2024\/10\/recolha-de-generos-alimentares\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;Recolha de g\u00e9neros alimentares&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":19740,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[55],"class_list":["post-19739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-eb1-de-alfarelos"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/19739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=19739"}],"version-history":[{"count":1,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/19739\/revisions"}],"predecessor-version":[{"id":19743,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/19739\/revisions\/19743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media\/19740"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=19739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=19739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=19739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}