{"id":19169,"date":"2024-04-26T09:36:00","date_gmt":"2024-04-26T08:36:00","guid":{"rendered":"https:\/\/www.escolasdesoure.pt\/web\/?p=19169"},"modified":"2024-04-26T09:36:52","modified_gmt":"2024-04-26T08:36:52","slug":"projeto-roc-mobilidade-na-lituania","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2024\/04\/projeto-roc-mobilidade-na-lituania\/","title":{"rendered":"Projeto ROC &#8211; mobilidade na Litu\u00e2nia"},"content":{"rendered":"\n<p>Entre os dias 15 e 19 abril, no \u00e2mbito do projeto Rangers of Change (ROC), decorreu a \u00faltima mobilidade Erasmus+, na Litu\u00e2nia, onde tivemos a oportunidade emocionante de mergulhar na rica cultura e paisagens deslumbrantes deste pa\u00eds b\u00e1ltico.<\/p>\n\n\n\n<p>Queremos partilhar algumas das nossas experi\u00eancias inesquec\u00edveis!<\/p>\n\n\n\n<p>A rece\u00e7\u00e3o decorreu na manh\u00e3 de segunda-feira, dia 15, na escola de Gra\u017ei\u0161kiai, onde fomos calorosamente recebidos pelos colegas e professores locais, tendo cada escola parceira partilhado as suas apresenta\u00e7\u00f5es. Na parte da tarde, sa\u00edmos para realizar uma a\u00e7\u00e3o de <em>plogging<\/em> no Parque Regional de Vistytis, mas para grande surpresa nossa, nada havia para limpar, pois tal como entretanto nos apercebemos, na Litu\u00e2nia todos os espa\u00e7os s\u00e3o extremamente limpos. Aproveit\u00e1mos assim para apreciar o deslumbrante ambiente natural e os lagos tranquilos de \u00e1gua cristalina. Logo a seguir, explor\u00e1mos o palacete Paezeriai Manor, atualmente um centro cultural, onde fomos recebidos com um breve espet\u00e1culo de m\u00fasica tradicional lituana, interpretado com instrumentos nacionais.<\/p>\n\n\n\n<p>No dia 16, ter\u00e7a-feira, fomos honrados com a rece\u00e7\u00e3o do presidente do munic\u00edpio de Vilkavi\u0161kis. Nessa sess\u00e3o fic\u00e1mos a conhecer a hist\u00f3ria e o desenvolvimento da cidade. De tarde, particip\u00e1mos em workshops de arte e pl\u00e1stico recicl\u00e1vel na Escola da Natureza de Kardokai. Foi uma experi\u00eancia educativa e inspiradora, onde aprendemos sobre a import\u00e2ncia da sustentabilidade e da preserva\u00e7\u00e3o ambiental, demos asas \u00e0 criatividade, enquanto nos&nbsp; sensibilizou para a import\u00e2ncia de cuidar do ambiente.<\/p>\n\n\n\n<p>O terceiro dia da nossa mobilidade, iniciou-se no Parque Regional de Meteliai, onde desfrut\u00e1mos de uma experi\u00eancia envolvente com a natureza. Come\u00e7\u00e1mos com uma emocionante observa\u00e7\u00e3o de aves no lago Dusia, onde avist\u00e1mos diversas esp\u00e9cies numa paisagem de beleza excecional. Fizemos ainda um percurso de cerca de 6 km pela floresta, explorando os trilhos e descobrindo a rica biodiversidade deste ecossistema intocado.<\/p>\n\n\n\n<p>Na quinta-feira, partimos cedo para Vilnius, a capital da Litu\u00e2nia, para uma experi\u00eancia educativa e cultural enriquecedora. Visit\u00e1mos o <em>Europe Direct Centre<\/em>, onde particip\u00e1mos em diversas atividades que nos proporcionam a oportunidade \u00fanica para aprender mais sobre a Uni\u00e3o Europeia, os seus programas e iniciativas, com jogos interativos e trabalhos em grupos transnacionais. De tarde, um outro jogo permitiu-nos explorar a cidade de Vilnius, passeando pelas ruas pitorescas do centro hist\u00f3rico e descobrindo tesouros como a Catedral de Santa Anna e a Avenida de Gediminas. No regresso, fizemos uma curta paragem em Trakai, a antiga capital do pa\u00eds, conhecida pelo seu castelo situado numa ilha no meio de um lago.<\/p>\n\n\n\n<p>No quinto e \u00faltimo dia da nossa jornada, test\u00e1mos os conhecimentos em ci\u00eancia, geografia e outros t\u00f3picos num <em>Brain Battle<\/em>, em equipas com os parceiros europeus. Foi uma oportunidade empolgante de trabalhar com os colegas, demonstrando os nossos conhecimentos. Depois destas atividades, recebemos os nossos certificados. Esta foi uma recompensa merecida n\u00e3o s\u00f3 pela nossa participa\u00e7\u00e3o nesta mobilidade, mas tamb\u00e9m pelo empenho e dedica\u00e7\u00e3o ao longo dos dois \u00faltimos anos de implementa\u00e7\u00e3o do projeto. Na parte da tarde, ainda nos foi proporcionada uma visita e realiza\u00e7\u00e3o de workshops criativos de ci\u00eancia e <em>media<\/em> no Centro <em>STEAM<\/em> de Marijampole.<\/p>\n\n\n\n<p>Esta mobilidade foi uma oportunidade \u00fanica e certamente memor\u00e1vel para partilhar experi\u00eancias, realizar aprendizagens significativas e criar la\u00e7os fortes independentemente das diferen\u00e7as culturais e lingu\u00edsticas.<\/p>\n\n\n\n<p>Laura A. &amp; Matilde G.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mobility in Lithuania, April 2024\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/r4REwIYvFDk?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Entre os dias 15 e 19 abril, no \u00e2mbito do projeto Rangers of Change (ROC), decorreu a \u00faltima mobilidade Erasmus+, na Litu\u00e2nia, onde tivemos a<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2024\/04\/projeto-roc-mobilidade-na-lituania\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;Projeto ROC &#8211; mobilidade na Litu\u00e2nia&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":17530,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[306,392],"class_list":["post-19169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-erasmus","tag-roc-rangers-of-change"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/19169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=19169"}],"version-history":[{"count":1,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/19169\/revisions"}],"predecessor-version":[{"id":19170,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/19169\/revisions\/19170"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media\/17530"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=19169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=19169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=19169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}