{"id":18787,"date":"2024-03-09T12:35:30","date_gmt":"2024-03-09T12:35:30","guid":{"rendered":"https:\/\/www.escolasdesoure.pt\/web\/?p=18787"},"modified":"2024-03-18T08:59:57","modified_gmt":"2024-03-18T08:59:57","slug":"projeto-roc-mobilidade-no-aemas","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2024\/03\/projeto-roc-mobilidade-no-aemas\/","title":{"rendered":"Projeto ROC: mobilidade no AEMAS"},"content":{"rendered":"\n<p>No \u00e2mbito do projeto <strong><em>Rangers of Change,<\/em><\/strong> enquadrado no programa Erasmus + e coordenado pela docente Alexandra Duarte, decorreu a quarta mobilidade, agora, em solo luso, entre os dias 26 de fevereiro e 1 de mar\u00e7o. Este encontro multicultural e plurilinguista reuniu alunos e professores, provenientes de escolas dos pa\u00edses parceiros- Espanha, Gr\u00e9cia, litu\u00e2nia e Rom\u00e9nia- imbu\u00eddos do mesmo esp\u00edrito de prote\u00e7\u00e3o do planeta, atrav\u00e9s de boas pr\u00e1ticas ambientais, de que s\u00e3o exemplos as diversas iniciativas desenvolvidas pelos alunos da nossa escola, nomeadamente sinal\u00e9tica para a poupan\u00e7a de energia e feira das trocas, entre outras. Integrado no programa do projeto supracitado, os alunos estrangeiros, recebidos calorosa e gentilmente pelas fam\u00edlias dos nossos alunos, tiveram a oportunidade de mergulhar no universo escolar e cultural portugu\u00eas, ao acompanhar os colegas nalgumas atividades letivas e ao confraternizar nos momentos de lazer e de cultura. Com o objetivo de consciencializar para a preserva\u00e7\u00e3o do meio ambiente, diversos foram os locais selecionados percorridos pela comitiva ROC, desde o parque dos Bacelos, onde plantaram simbolicamente \u00e1rvores, \u00e0 Ersuc, em Vil de Matos e \u00e0 Ecogr\u00e9s em \u00cdlhavo, uma das f\u00e1bricas de gr\u00e9s mais sustent\u00e1vel do mundo. Em Aveiro, todos os participantes envolvidos no projeto navegaram nas \u00e1guas da laguna da Foz do Vouga, vulgo Ria de Aveiro, precisamente no Salgado da Ria de Aveiro, no qual seguiram a Rota Birdwatching, a cargo da empresa Sterna Aveiro Ria Tours &amp; Birdwatching. Ao longo do trajeto, subiram o Canal da Veia (art\u00e9ria principal para a entrada de embarca\u00e7\u00f5es para o antigo Porto Comercial) para observar a nidifica\u00e7\u00e3o de algumas aves (corvos marinhos, gar\u00e7as, gaivotas) e os palheiros onde os marnotos colocavam as suas alfaias. Simultaneamente, ouviram-se hist\u00f3rias \/ est\u00f3rias sobre a produ\u00e7\u00e3o de sal, o abandono das salinas, o tratamento\/a faina do bacalhau. Por fim, foi poss\u00edvel acompanhar parte do processo de produ\u00e7\u00e3o de ostras da empresa Ostraveiro, a partir do ber\u00e7\u00e1rio at\u00e9 \u00e0 retirada da \u00e1gua, atividade que culminou na degusta\u00e7\u00e3o de ovos moles, doce t\u00edpico da regi\u00e3o.<\/p>\n\n\n\n<p>As iniciativas culturais estiveram tamb\u00e9m presentes nesta jornada lingu\u00edstica com a visita a Coimbra, concretamente \u00e0 Europe Direct, \u00e0 Universidade de Coimbra e \u00e0 C\u00e2mara Municipal desta cidade.<\/p>\n\n\n\n<p>O vasto e diversificado programa, que teve in\u00edcio com a rece\u00e7\u00e3o, em l\u00edngua inglesa, feita pelos representantes m\u00e1ximos da escola e da C\u00e2mara Municipal, e pela coordenadora do projeto, culminou com grande anima\u00e7\u00e3o e festa inclusiva, pois \u201cEnsinar e Aprender \u00e9 uma festa!\u201d<\/p>\n\n\n\n<p>A todos quanto participaram nesta aventura ecol\u00f3gica e internacional, o nosso muito obrigado, em particular \u00e0 C\u00e2mara Municipal de Soure que tornou poss\u00edvel a concretiza\u00e7\u00e3o desta mobilidade ao mais alto n\u00edvel. <strong><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Mobilidade Rangers of Change (ROC) em Portugal\" width=\"1170\" height=\"658\" src=\"https:\/\/www.youtube.com\/embed\/IGGEmm7R9-g?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>No \u00e2mbito do projeto Rangers of Change, enquadrado no programa Erasmus + e coordenado pela docente Alexandra Duarte, decorreu a quarta mobilidade, agora, em solo<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2024\/03\/projeto-roc-mobilidade-no-aemas\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;Projeto ROC: mobilidade no AEMAS&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":17530,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[306,392],"class_list":["post-18787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-erasmus","tag-roc-rangers-of-change"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/18787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=18787"}],"version-history":[{"count":2,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/18787\/revisions"}],"predecessor-version":[{"id":18816,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/18787\/revisions\/18816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media\/17530"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=18787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=18787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=18787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}