{"id":1605,"date":"2011-03-14T10:21:28","date_gmt":"2011-03-14T10:21:28","guid":{"rendered":"http:\/\/www.escolasdesoure.pt\/web\/?p=1605"},"modified":"2011-03-14T10:21:56","modified_gmt":"2011-03-14T10:21:56","slug":"ferias-2010","status":"publish","type":"post","link":"https:\/\/www.escolasdesoure.pt\/web\/2011\/03\/ferias-2010\/","title":{"rendered":"Pessoal Docente: F\u00e9rias 2011"},"content":{"rendered":"<p style=\"text-align: justify;\">Informa-se o Pessoal Docente que se encontra dispon\u00edvel o modelo para marca\u00e7\u00e3o da licen\u00e7a para f\u00e9rias\/2011.<\/p>\n<p style=\"text-align: justify;\">Dever\u00e1 ser devolvido at\u00e9 ao dia 31 de Mar\u00e7o de 2011.<\/p>\n<p style=\"text-align: justify;\">A licen\u00e7a para f\u00e9rias deve ser gozada entre o dia 25 de Julho e o dia 31 de Agosto de 2011.<\/p>\n<p style=\"text-align: center;\">Soure, 11 de Mar\u00e7o de 2011<br \/>\nO Director<br \/>\nJo\u00e3o Augusto de Castro Ramos Pereira<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informa-se o Pessoal Docente que se encontra dispon\u00edvel o modelo para marca\u00e7\u00e3o da licen\u00e7a para f\u00e9rias\/2011. Dever\u00e1 ser devolvido at\u00e9 ao dia 31 de Mar\u00e7o<a href=\"https:\/\/www.escolasdesoure.pt\/web\/2011\/03\/ferias-2010\/\" class=\"more-link\"><span class=\"screen-reader-text\"> &#8220;Pessoal Docente: F\u00e9rias 2011&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1605","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/1605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/comments?post=1605"}],"version-history":[{"count":6,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/1605\/revisions"}],"predecessor-version":[{"id":3159,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/posts\/1605\/revisions\/3159"}],"wp:attachment":[{"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/media?parent=1605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/categories?post=1605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escolasdesoure.pt\/web\/wp-json\/wp\/v2\/tags?post=1605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}